{"id":10526,"date":"2020-10-30T17:20:13","date_gmt":"2020-10-30T16:20:13","guid":{"rendered":"https:\/\/complex-systems-ai.com\/?page_id=10526"},"modified":"2024-02-13T08:09:08","modified_gmt":"2024-02-13T07:09:08","slug":"exercices-file-dattente","status":"publish","type":"page","link":"https:\/\/complex-systems-ai.com\/es\/proceso-de-markov\/ejercicios-corregidos-cola\/","title":{"rendered":"8 Ejercicios corregidos: Cola"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10526\" class=\"elementor elementor-10526\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f383866 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f383866\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2132105\" data-id=\"2132105\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2cda77 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"a2cda77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/complex-systems-ai.com\/processus-de-markov\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Proessus stochastique<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2041593\" data-id=\"2041593\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d9f250 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"9d9f250\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/complex-systems-ai.com\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Page d'accueil<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ebafd29\" data-id=\"ebafd29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-388a152 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"388a152\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Processus_stochastique\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Wiki<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66287fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66287fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-92353a4\" data-id=\"92353a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eac75f elementor-widget elementor-widget-heading\" data-id=\"3eac75f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenus<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/complex-systems-ai.com\/es\/proceso-de-markov\/ejercicios-corregidos-cola\/#Exercices-corriges-File-dattente\" >Exercices corrig\u00e9s : File d'attente<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/complex-systems-ai.com\/es\/proceso-de-markov\/ejercicios-corregidos-cola\/#Exercice-1\" >Exercice 1<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/complex-systems-ai.com\/es\/proceso-de-markov\/ejercicios-corregidos-cola\/#Exercice-2\" >Exercice 2<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/complex-systems-ai.com\/es\/proceso-de-markov\/ejercicios-corregidos-cola\/#Exercice-3\" >Exercice 3<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/complex-systems-ai.com\/es\/proceso-de-markov\/ejercicios-corregidos-cola\/#Exercice-4\" >Exercice 4<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/complex-systems-ai.com\/es\/proceso-de-markov\/ejercicios-corregidos-cola\/#Exercice-5\" >Exercice 5<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/complex-systems-ai.com\/es\/proceso-de-markov\/ejercicios-corregidos-cola\/#Exercice-6\" >Exercice 6<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/complex-systems-ai.com\/es\/proceso-de-markov\/ejercicios-corregidos-cola\/#Exercice-7\" >Exercice 7<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/complex-systems-ai.com\/es\/proceso-de-markov\/ejercicios-corregidos-cola\/#Exercice-8\" >Exercice 8<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Exercices-corriges-File-dattente\"><\/span>Exercices corrig\u00e9s : File d'attente<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91d63ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91d63ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-587ddf3\" data-id=\"587ddf3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e03b3f elementor-widget elementor-widget-text-editor\" data-id=\"1e03b3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les exercices corrig\u00e9s ci-dessous concernent la file d&rsquo;attente, les chaines de Markov en temps continu.<\/p><p><img decoding=\"async\" class=\"aligncenter wp-image-11096 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/09\/cropped-Capture.png\" alt=\"file d&#039;attente\" width=\"97\" height=\"97\" title=\"\"><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c3bdaba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c3bdaba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-682c6c1\" data-id=\"682c6c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc1c15c elementor-widget elementor-widget-heading\" data-id=\"cc1c15c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Exercice-1\"><\/span>Exercice 1<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2591244 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2591244\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-767f9ad\" data-id=\"767f9ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-303abe8 elementor-widget elementor-widget-text-editor\" data-id=\"303abe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un syst\u00e8me clients-serveur re\u00e7oit en moyenne 1000 requ\u00eates par seconde, arrivant selon un processus de Poisson. Il dispose d\u2019un unique serveur pouvant traiter en moyenne 2000 clients par seconde. On suppose que le temps de service d\u2019un client est distribu\u00e9 selon la loi exponentielle. Calculer la probabilit\u00e9 que le temps de service d\u00e9passe 2 ms.<\/p><p>Quelle est le pourcentage de clients rejet\u00e9s pour un syst\u00e8me ne comportant pas de file d\u2019attente.<\/p><p>M\u00eame question pour un syst\u00e8me comportant une file d\u2019attente de 1 place. Calculer le taux d\u2019application du serveur.<\/p><p>M\u00eame question pour un syst\u00e8me comportant une file d\u2019attente de 2 places.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4efd0d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4efd0d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-620c8ad\" data-id=\"620c8ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab5f1e9 elementor-widget elementor-widget-toggle\" data-id=\"ab5f1e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1791\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1791\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Solution<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1791\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1791\"><p>En choisissant la milliseconde comme unit\u00e9 de temps on obtient un taux de naissance de 1 et un taux de d\u00e9c\u00e8s de 2. Le temps de service T<sub>S<\/sub>\u00a0d\u2019un client suit une loi exponentielle de param\u00e8tre 2 donc la probabilit\u00e9 que le temps de service d\u00e9passe deux secondes est de 0.0183 gr\u00e2ce \u00e0 la formule suivant\u00a0:<\/p><p><img decoding=\"async\" class=\"aligncenter wp-image-10532 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image96.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"180\" height=\"33\" title=\"\"><\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-10533 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image97.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"406\" height=\"132\" title=\"\" srcset=\"https:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image97.png 406w, https:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image97-300x98.png 300w\" sizes=\"(max-width: 406px) 100vw, 406px\" \/><\/p><p>La chaine (a) repr\u00e9sente une capacit\u00e9 dans la file de 0 place tandis que la chaine (b) repr\u00e9sente une capacit\u00e9 dans la file de 1 place. Pour chaque nouvelle place il suffit de rajouter un \u00e9tat.<\/p><p>Pour la premi\u00e8re chaine, nous allons calculer la distribution stationnaire\u00a0:<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10534 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image98.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"173\" height=\"78\" title=\"\"><\/p><p>Nous avons donc 1\/3 de clients rejet\u00e9s (si on se trouve 1\/3 du temps en \u00e9tat 1, alors on ne peut plus recevoir des clients sur 1\/3 du fonctionnement de la file). Le taux d\u2019occupation est pi<sub>0<\/sub>\u00a0= 2\/3.<\/p><p>Pour la deuxi\u00e8me chaine, nous allons calculer la distribution stationnaire\u00a0:<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10536 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image99.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"90\" height=\"118\" title=\"\"><\/p><p>Et pour une capacit\u00e9 de 2 dans la file d\u2019attente nous obtenons pi<sub>3<\/sub>\u00a0= 1\/15 et pi<sub>0<\/sub>\u00a0= 8\/15.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc9bd84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc9bd84\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1df155e\" data-id=\"1df155e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e65aaa elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6e65aaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35b9779 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35b9779\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e595568\" data-id=\"e595568\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2b1cfc elementor-widget elementor-widget-heading\" data-id=\"c2b1cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Exercice-2\"><\/span>Exercice 2<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec38828 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec38828\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fcec7fd\" data-id=\"fcec7fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bad253a elementor-widget elementor-widget-text-editor\" data-id=\"bad253a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un syst\u00e8me clients-serveur re\u00e7oit en moyenne 1000 requ\u00eates par seconde, arrivant selon un processus de Poisson. A titre exp\u00e9rimental, on envisage un syst\u00e8me sans file d\u2019attente mais comportant plusieurs serveurs de front. Lorsque tous les serveurs sont occup\u00e9s, les requ\u00eates sont rejet\u00e9es.<\/p><p>Quelle est le pourcentage de clients rejet\u00e9s pour un syst\u00e8me comportant 1 serveur traitant 4000 requ\u00eates par seconde<\/p><p>M\u00eame question pour un syst\u00e8me comportant deux serveurs traitant chacun 2000 requ\u00eates par seconde.<\/p><p>M\u00eame question pour un syst\u00e8me comportant quatre serveurs traitant chacun 1000 requ\u00eates par seconde.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-960dd91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"960dd91\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1859ef\" data-id=\"e1859ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfbffed elementor-widget elementor-widget-toggle\" data-id=\"bfbffed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2011\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2011\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Solution<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2011\"><p>Peu importe le nombre de serveur, l\u2019id\u00e9e du calcul parall\u00e8le sans file d\u2019attente est toujours construite de la m\u00eame mani\u00e8re\u00a0: \u00e0 chaque nouveau client, un serveur de plus fonctionne.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10537 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image100.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"434\" height=\"233\" title=\"\" srcset=\"https:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image100.png 434w, https:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image100-300x161.png 300w\" sizes=\"(max-width: 434px) 100vw, 434px\" \/><\/p><p>Il suffit de calculer la distribution stationnaire, le nombre de client rejet\u00e9 est \u00e9gale \u00e0 la distribution du dernier \u00e9tat (le plus \u00e0 droite ici).<\/p><p>Pour un serveur\u00a0: 1\/5<\/p><p>Pour deux serveurs\u00a0: 1\/13<\/p><p>Pour quatre serveurs\u00a0: 1\/65<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77edd48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77edd48\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b3eb426\" data-id=\"b3eb426\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-731bc8e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"731bc8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c32e0d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c32e0d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77456f7\" data-id=\"77456f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82a6b14 elementor-widget elementor-widget-heading\" data-id=\"82a6b14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Exercice-3\"><\/span>Exercice 3<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39d3408 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39d3408\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39ad32c\" data-id=\"39ad32c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f91f07 elementor-widget elementor-widget-text-editor\" data-id=\"3f91f07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Des camions arrivent dans une station-service pour passer des tests de s\u00e9curit\u00e9, suivant un processus de Poisson de taux de 6\u00a0\/\u00a0jour. La dur\u00e9e des tests pour chaque camion est une v.a exponentielle d&rsquo;esp\u00e9rance math\u00e9matique de 1h 30\u00a0mn. On suppose que le processus d&rsquo;arriv\u00e9e ne s&rsquo;interrompt pas et que la station travaille 24\u00a0heures sur 24.<\/p><p>Le syst\u00e8me admet-il une distribution stationnaire\u00a0?<\/p><p>Si oui la calculer et donner le nombre moyen d&rsquo;usagers dans le syst\u00e8me, le temps moyen pass\u00e9 dans le syst\u00e8me, la longueur moyenne de la file d&rsquo;attente et le temps moyen pass\u00e9 dans la file (en r\u00e9gime stationnaire).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d9e043 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d9e043\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22a365b\" data-id=\"22a365b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a11171d elementor-widget elementor-widget-toggle\" data-id=\"a11171d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1681\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1681\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Solution<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1681\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1681\"><p>Nous avons lambda=1\/4\u00a0 et mu=2\/3\u00a0 (en heure). Comme rho=3\/8&lt;1 , le syst\u00e8me est ergodique. D&rsquo;apr\u00e8s les formules du calcul des param\u00e8tres des syst\u00e8mes\u00a0 M\/M\/1, nous aurons :<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10538 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image101.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"308\" height=\"48\" title=\"\" srcset=\"https:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image101.png 308w, https:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image101-300x47.png 300w\" sizes=\"(max-width: 308px) 100vw, 308px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10539 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image102.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"257\" height=\"44\" title=\"\">La longueur moyenne de la file d&rsquo;attente et la dur\u00e9e d&rsquo;attente dans la file sont donn\u00e9es par :<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10540 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image103.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"160\" height=\"38\" title=\"\"><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10541 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image104.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"371\" height=\"41\" title=\"\" srcset=\"https:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image104.png 371w, https:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image104-300x33.png 300w\" sizes=\"(max-width: 371px) 100vw, 371px\" \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c84a7e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c84a7e8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d364442\" data-id=\"d364442\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a3d831 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9a3d831\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8167316 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8167316\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-890e642\" data-id=\"890e642\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c35fea3 elementor-widget elementor-widget-heading\" data-id=\"c35fea3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Exercice-4\"><\/span>Exercice 4<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-799fdda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"799fdda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-467caa1\" data-id=\"467caa1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7de71f elementor-widget elementor-widget-text-editor\" data-id=\"e7de71f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une entreprise de construction poss\u00e8de deux engins identiques, chacun pouvant tomber en panne ind\u00e9pendamment de l&rsquo;autre suivant un processus de Poisson de taux 5 fois par mois. On suppose que la dur\u00e9e de r\u00e9paration est une v.a. qui suit une loi exponentielle de param\u00e8tre mu\u00a0(taux de service). Pour quelle valeur de mu, les deux engins seront-ils simultan\u00e9ment en \u00e9tat de marche au moins la moiti\u00e9 du temps ?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae73f75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae73f75\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c4b0d39\" data-id=\"c4b0d39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e53de99 elementor-widget elementor-widget-toggle\" data-id=\"e53de99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2401\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2401\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Solution<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2401\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2401\"><p>Le syst\u00e8me est mod\u00e9lis\u00e9 par un processus de naissance et de mort \u00e0 3 \u00e9tats (0, 1 ou 2 machines en panne) de diagramme de transition suivant\u00a0:<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10542 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image105.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"166\" height=\"48\" title=\"\"><\/p><p>Nous avons\u00a0:<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10543 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image106.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"187\" height=\"50\" title=\"\"><\/p><p>D&rsquo;o\u00f9<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10544 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image107.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"279\" height=\"58\" title=\"\"><br \/>p0\u00a0\u00e9tant la probabilit\u00e9 stationnaire pour que les deux engins soient en \u00e9tat de marche, on devra avoir\u00a0:<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10545 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image108.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"231\" height=\"69\" title=\"\"><\/p><p>Tenant compte de la positivit\u00e9 de mu, on doit avoir<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10546 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image109.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"280\" height=\"28\" title=\"\"><\/p><p>Il faudra donc un taux de service au moins \u00e9gal \u00e0 \u00a0\u00a0<strong><b>13,660254<\/b><\/strong>\u00a0pour que les deux engins soient en \u00e9tat de marche au moins une fois sur deux.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bb9de0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bb9de0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e52d744\" data-id=\"e52d744\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a44e71 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8a44e71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83e6fdc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83e6fdc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-557bd9c\" data-id=\"557bd9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76bd01a elementor-widget elementor-widget-heading\" data-id=\"76bd01a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Exercice-5\"><\/span>Exercice 5<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be16872 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be16872\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6cb5584\" data-id=\"6cb5584\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-385996e elementor-widget elementor-widget-text-editor\" data-id=\"385996e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une blanchisserie poss\u00e8de 3 machines identiques et ind\u00e9pendantes. Chaque machine a une dur\u00e9e de fonctionnement ind\u00e9pendante du pass\u00e9, suivant une loi exponentielle d&rsquo;esp\u00e9rance de deux jours. Une machine qui tombe en panne est r\u00e9par\u00e9e par un technicien\u00a0; la dur\u00e9e de r\u00e9paration est une v.a. d&rsquo;esp\u00e9rance d&rsquo;un jour. La blanchisserie n&rsquo;a qu&rsquo;un technicien.<\/p><p>Dessiner le diagramme de transition.<\/p><p>Quelle est la fraction de temps o\u00f9 toutes les machines fonctionnent et celle o\u00f9 toutes les machines sont hors service\u00a0?<\/p><p>Quel est le nombre moyen de machines en \u00e9tat de marche\u00a0? Quel est le nombre moyen de machines immobilis\u00e9es\u00a0?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b51dd1a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b51dd1a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-abe5a4c\" data-id=\"abe5a4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a778f54 elementor-widget elementor-widget-toggle\" data-id=\"a778f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1751\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1751\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Solution<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1751\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1751\"><ol><li>Supposons que l&rsquo;\u00e9tat Ej d\u00e9signe l&rsquo;\u00e9tat dans lequel j machines sont immobilis\u00e9es. Nous avons le diagramme de transition suivant : <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10547 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image110.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"253\" height=\"53\" title=\"\"><\/li><li><b><\/b>Nous avons en r\u00e9gime stationnaire les \u00e9quations suivantes : <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10548 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image111.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"294\" height=\"46\" title=\"\">D&rsquo;o\u00f9 <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10549 size-full\" src=\"http:\/\/complex-systems-ai.com\/wp-content\/uploads\/2020\/10\/Image112.png\" alt=\"exercices corrig\u00e9s file d&#039;attente\" width=\"290\" height=\"48\" title=\"\"><p>Les fractions recherch\u00e9es sont donc 4\/19\u00a0 (pour toutes les machines en marche) et\u00a0 3\/19 (pour toutes les machines immobilis\u00e9es).<\/p><\/li><li><b><\/b>Le nombre moyen de machines en \u00e9tat de marche vaut : 4*(4\/19)+2*(6\/19)+1*(6\/19)=30\/19. Et le nombre moyen de machines immobilis\u00e9es vaut 9\/19+12\/19+6\/193.<\/li><\/ol><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d18d18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d18d18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e12274a\" data-id=\"e12274a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ebc238 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0ebc238\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a7080c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a7080c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-603ca91\" data-id=\"603ca91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b6e680 elementor-widget elementor-widget-heading\" data-id=\"1b6e680\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Exercice-6\"><\/span>Exercice 6<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aad363a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aad363a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32d851d\" data-id=\"32d851d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30ec37a elementor-widget elementor-widget-text-editor\" data-id=\"30ec37a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un serveur de base de donn\u00e9es re\u00e7oit en moyenne 100 requ\u00eates par seconde, arrivant selon un processus de Poisson. Le temps de traitement d\u2019une requ\u00eate suit la loi exponentielle de param\u00e8tre \u00b5. Quand le serveur est occup\u00e9, les requ\u00eates sont stock\u00e9es sur un disque de grande taille pour \u00eatre trait\u00e9es ult\u00e9rieurement selon le principe \u201dpremier arriv\u00e9, premier servi\u201d. Il existe, sur le march\u00e9, 4 types diff\u00e9rents de serveurs pouvant traiter respectivement 100, 150, 200 ou 300 requ\u00eates par seconde quand ils fonctionnent sans interruption.<\/p><p>Que se passera-t-il si l\u2019on pr\u00e9voit d\u2019installer un serveur pouvant traiter 100 requ\u00eates par seconde ?<\/p><p>On souhaite qu\u2019un client qui \u00e9met une requ\u00eate ait la r\u00e9ponse au bout de 1\/100 seconde en moyenne. Quel type de serveur faut-il pr\u00e9voir ?<\/p><p>On convient que lorsqu\u2019il y a d\u00e9j\u00e0 8 requ\u00eates stock\u00e9es dans la file d\u2019attente, les nouvelles requ\u00eates arrivantes seraient trop p\u00e9nalis\u00e9es au niveau du temps de r\u00e9ponse. Donc on d\u00e9cide que dans ce cas, elles seront redirig\u00e9es instantan\u00e9ment sur un serveur auxiliaire. Pour simplifier, on supposera que cette nouvelle disposition a une influence n\u00e9gligeable sur l\u2019ancienne distribution stationnaire (calcul\u00e9e sans serveur auxiliaire). Calculer la probabilit\u00e9 qu\u2019une requ\u00eate qui arrive sur le serveur principal soit redirig\u00e9e sur le serveur auxiliaire. Combien, en moyenne, le serveur auxiliaire recevra-t-il de requ\u00eates par seconde ?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-032d199 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"032d199\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35d4190\" data-id=\"35d4190\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a79bd1 elementor-widget elementor-widget-toggle\" data-id=\"0a79bd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1091\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1091\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Solution<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1091\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1091\"><p>Il s\u2019agit d\u2019une file d\u2019attente M\/M\/1, nous pouvons donc utiliser les lois de Little. Il y a distribution stationnaire si \u03bb\/\u03bc&lt;1, si on prend un serveur qui traite 100\/seconde alors nous avons \u03bb\/\u03bc=1 la chaine n\u2019est pas ergodique\u00a0(accumulation infinie de requ\u00eate) !<\/p><p>Si on veut un temps de r\u00e9ponse de 1\/100 seconde alors nous devons r\u00e9soudre l\u2019\u00e9quation 1\/100=E(T)=1\/( \u03bc \u2013 \u03bb) donc \u03bc=200 requ\u00eates\/seconde.<\/p><p>Les requ\u00eates sont redirig\u00e9es s\u2019il y a d\u00e9j\u00e0 8 requ\u00eates dans le syst\u00e8me. Donc il y a redirection lorsque le syst\u00e8me atteint 9 requ\u00eates dans le syst\u00e8me. Il suffit de calculer \u03c0<sub>9<\/sub>\u00a0pour connaitre la probabilit\u00e9 que la requ\u00eate soit redirig\u00e9e. D\u2019apr\u00e8s la loi de Little \u03c0<sub>9<\/sub>\u00a0= (1 &#8211; \u03c1)\u00a0\u03c1<sup>9<\/sup>\u00a0=1\/1024.<\/p><p>Puisque le syst\u00e8me re\u00e7oit 100 requ\u00eates par seconde, le serveur auxiliaire re\u00e7oit 100\/1024 requ\u00eate par seconde.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-562d870 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"562d870\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3735cf5\" data-id=\"3735cf5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96c4633 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"96c4633\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e89db25 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e89db25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-472b9d6\" data-id=\"472b9d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0196ee5 elementor-widget elementor-widget-heading\" data-id=\"0196ee5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Exercice-7\"><\/span>Exercice 7<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d732c59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d732c59\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-acf7e5b\" data-id=\"acf7e5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d7a2b8 elementor-widget elementor-widget-text-editor\" data-id=\"8d7a2b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans une usine de production automobile, on a \u00e9tudi\u00e9 le probl\u00e8me de la d\u00e9termination du nombre optimal d\u2019employ\u00e9s \u00e0 placer aux guichets d\u2019un magasin charg\u00e9 de fournir l\u2019outillage n\u00e9cessaire aux ouvriers. L\u2019\u00e9tude du magasin a commenc\u00e9 par la d\u00e9termination des caract\u00e9ristiques statistiques des arriv\u00e9es des ouvriers (1.6 arriv\u00e9es\/minute) et des temps pass\u00e9s par les employ\u00e9s pour fournir les outillages demand\u00e9s (0.9 service\/minute).<\/p><p>Calculer le temps moyen d\u2019attente dans la file (W<sub>q<\/sub>) pour S=2, S=3, S=4.\u00a0Calculer le nombre moyen de clients dans une journ\u00e9e de 8 heures et le temps de service moyen correspondant.\u00a0Selon le nombre d\u2019employ\u00e9s (S), calculer le nombre d\u2019heures d\u2019inactivit\u00e9 par jour de 8 heures.<\/p><p>Calculer le temps perdu chaque jour par les ouvriers, du fait de l\u2019attente ?\u00a0Si le prix de revient horaire d\u2019un employ\u00e9 est 40,00 $ et celui d\u2019un ouvrier 80,00 $, quel est le co\u00fbt total des heures perdues\u00a0?<\/p><p>Conclure en donnant le nombre optimal d\u2019employ\u00e9s \u00e0 pr\u00e9voir pour le magasin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2af71d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2af71d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d816157\" data-id=\"d816157\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f70c07 elementor-widget elementor-widget-toggle\" data-id=\"7f70c07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1331\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1331\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Solution<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1331\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1331\"><p>Connaissant l et m, on a calcul\u00e9 l\/m = 1.6\/0.9 = 1.77 &gt; 1.<\/p><p>Puisque l\/m &gt; 1, on s\u2019est int\u00e9ress\u00e9 uniquement aux valeurs de S=2, S=3, et S=4.<\/p><p>Pour calculer le temps moyen d\u2019attente dans la file, on a d\u2019abord cherch\u00e9 P<sub>0<\/sub>, pour chaque valeur respective de S.<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0S=2, P<sub>0<\/sub>\u00a0= 0.061 S=3, P<sub>0<\/sub>\u00a0= 0.152 S=4, P<sub>0<\/sub>\u00a0= 0.166<\/p><p>ce qui donne<\/p><p>S=2, W<sub>q<\/sub>\u00a0= 4.00<\/p><p>S=3, W<sub>q<\/sub>\u00a0= 0.31<\/p><p>S=4, W<sub>q<\/sub>\u00a0= 0.06<\/p><p>Calculons maintenant le nombre moyen de clients dans une journ\u00e9e de 8 heures<\/p><p>l x 60 x 8= 1.6 x 60 x 8 = 768<\/p><p>et, pour ce nombre d\u2019arriv\u00e9es, il faudra (avec un temps de service de 1\/m)<\/p><p>768\/m = 768\/0.9 = 853 minutes de service par jour.<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 = 14.21 heures<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4979a6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4979a6d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f53128\" data-id=\"2f53128\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72217f1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"72217f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ea1a09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ea1a09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b975827\" data-id=\"b975827\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b131f3 elementor-widget elementor-widget-heading\" data-id=\"4b131f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Exercice-8\"><\/span>Exercice 8<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-633bcd7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"633bcd7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-91374c4\" data-id=\"91374c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cc863f elementor-widget elementor-widget-text-editor\" data-id=\"6cc863f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un laboratoire contient 2 micro-ordinateurs identiques. Les usagers arrivent selon un processus de Poisson de param\u00e8tre l = 3 usagers par heure. La dur\u00e9e d&rsquo;utilisation d&rsquo;un micro-ordinateur est une v.a. exponentielle de moyenne 0.6 heure (m = 1 \/ 0.6).<\/p><p>&#8211; Taux d&rsquo;utilisation du laboratoire<\/p><p>&#8211; Nombre d&rsquo;usagers dans la file<\/p><p>&#8211; Temps d&rsquo;attente dans la file<\/p><p>Le patron trouve que les gens perdent trop de temps \u00e0 attendre, et d\u00e9cide d&rsquo;ajouter des micro-ordinateurs. Il d\u00e9sire que le temps moyen d&rsquo;attente soit inf\u00e9rieur \u00e0 20 minutes. Combien doit-il en ajouter ? Quel est le nouveau taux d&rsquo;utilisation du laboratoire ?<\/p><p>Qu&rsquo;adviendrait-il en ce qui a trait au temps d&rsquo;attente des usagers si on les s\u00e9parait en 3 groupes, assignant un micro-ordinateur \u00e0 chaque groupe ?<\/p><p>Qu&rsquo;en concluez-vous ?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb7505a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb7505a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c24fd0\" data-id=\"8c24fd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58b84ff elementor-widget elementor-widget-toggle\" data-id=\"58b84ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9301\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9301\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Solution<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9301\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9301\"><p>On a une file d\u2019attente M\/M\/2.<\/p><p>r\u00a0= l\/2m\u00a0= 0.9<\/p><p>P0\u00a0= 1\/19 \u00a0\u00a0\u00a0P1\u00a0= l\/m\u00a0P0\u00a0= 1.8\/19<\/p><p>Q = [r\/1-r] (1 &#8211; P0\u00a0&#8211; P1) = 7.674<\/p><p>Wq\u00a0= 2.56 h<\/p><p>Le syst\u00e8me n\u2019est utilis\u00e9 qu\u2019\u00e0 90%, mais chaque usager doit attendre en moyenne plus de 2 heures 30.<\/p><p>Le patron trouve que les gens perdent trop de temps \u00e0 attendre et d\u00e9cide d\u2019ajouter des micro-ordinateurs. \u00a0Il veut que le temps moyen d\u2019attente soit inf\u00e9rieur \u00e0 20 minutes. \u00a0Combien doit-il en ajouter ?<\/p><p>On peut essayer avec plusieurs valeurs de S = s, et calculer Wq\u00a0pour chaque cas\u00a0:<\/p><p>s=3<\/p><p>Q=0.532<\/p><p>Wq=0.177 h. \u00bb 10.6 min<\/p><p>Avec 3 micro-ordinateurs, la contrainte est satisfaite, mais le taux d\u2019utilisation du syst\u00e8me est maintenant de r\u00a0= 0.6.<\/p><p>Qu\u2019adviendrait-il si on s\u00e9parait les usagers en 3 groupes, assignant un micro-ordinateur \u00e0 chaque groupe ?<\/p><p>On a maintenant 3 files d\u2019attente M\/M\/1, chacune ayant un taux d\u2019arriv\u00e9e l\u00a0= 3\/3 = 1, un taux de service m\u00a0= 1\/0.6 et un facteur d\u2019utilisation r\u00a0= 0.6.<\/p><p>On obtient :<\/p><p>Wq = r\u00b2\/[l(1-r)] = 0.9 heure<\/p><p>= 54 min.<\/p><p>Il est donc pr\u00e9f\u00e9rable de partager les ressources.<\/p><p>Ainsi,<\/p><p>S = 2 employ\u00e9s auraient 2 x 8 &#8211; 14.21 = 1.79 heures d\u2019inactivit\u00e9 par jour<\/p><p>S = 3 employ\u00e9s auraient 3 x 8 &#8211; 14.21 = 9.79 heures d\u2019inactivit\u00e9 par jour<\/p><p>S = 4 employ\u00e9s auraient 4 x 8 &#8211; 14.21 = 17.79 heures d\u2019inactivit\u00e9 par jour<\/p><p>Cherchons maintenant le temps perdu chaque jour par les ouvriers, du fait de l\u2019attente :<\/p><p>S = 2 768 x 4 = 3072 min. = 51.2 heures<\/p><p>S = 3 768 x 0.31 = 238 min. = 3.96 heures<\/p><p>S = 4 768 x 0.06 = 46 min. = 0.76 heures<\/p><p>Le co\u00fbt total des heures perdues a pour valeur :<\/p><p>S = 2 $ 4 167.60 = 1.79 x 40 + 51.2 x 80<\/p><p>S = 3 $ 708.40 = 9.79 x 40 + 3.96 x 80 the best one !<\/p><p>S = 4 $ 772.40 = 17.79 x 40 + 0.76 X 80<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Proceso estoc\u00e1stico P\u00e1gina de inicio de Wiki Ejercicios corregidos: Cola Los ejercicios corregidos a continuaci\u00f3n se refieren a la cola, cadenas de Markov en tiempo continuo. \u2026 <\/p>","protected":false},"author":1,"featured_media":0,"parent":5007,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10526","page","type-page","status-publish","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/complex-systems-ai.com\/es\/wp-json\/wp\/v2\/pages\/10526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/complex-systems-ai.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/complex-systems-ai.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/complex-systems-ai.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/complex-systems-ai.com\/es\/wp-json\/wp\/v2\/comments?post=10526"}],"version-history":[{"count":4,"href":"https:\/\/complex-systems-ai.com\/es\/wp-json\/wp\/v2\/pages\/10526\/revisions"}],"predecessor-version":[{"id":20557,"href":"https:\/\/complex-systems-ai.com\/es\/wp-json\/wp\/v2\/pages\/10526\/revisions\/20557"}],"up":[{"embeddable":true,"href":"https:\/\/complex-systems-ai.com\/es\/wp-json\/wp\/v2\/pages\/5007"}],"wp:attachment":[{"href":"https:\/\/complex-systems-ai.com\/es\/wp-json\/wp\/v2\/media?parent=10526"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}